{"id":11848,"date":"2026-07-15T07:29:02","date_gmt":"2026-07-15T12:29:02","guid":{"rendered":"https:\/\/elchiq.com\/?p=11848"},"modified":"2026-07-15T07:29:02","modified_gmt":"2026-07-15T12:29:02","slug":"argentina-vs-inglaterra-la-sangre-del-diego-en-el-talento-de-leo","status":"publish","type":"post","link":"https:\/\/elchiq.com\/index.php\/2026\/07\/15\/argentina-vs-inglaterra-la-sangre-del-diego-en-el-talento-de-leo\/","title":{"rendered":"Argentina vs Inglaterra: La sangre del Diego en el talento de Leo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Argentina e Inglaterra reviven la rivalidad que se intensific\u00f3 en el Mundial de M\u00e9xico en 1986.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"570\" height=\"321\" src=\"https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/image-66.png\" alt=\"\" class=\"wp-image-11849\" style=\"aspect-ratio:1.7757873728277271;width:948px;height:auto\" srcset=\"https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/image-66.png 570w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/image-66-300x169.png 300w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por: redacci\u00f3n ESPN y elchiq.com\u00a0 <a href=\"https:\/\/www.google.com\/search?q=elchiq&amp;oq=elch&amp;gs_lcrp=EgZjaHJvbWUqDggAEEUYJxg7GIAEGIoFMg4IABBFGCcYOxiABBiKBTIPCAEQLhhDGLEDGIAEGIoFMg8IAhAuGEMYsQMYgAQYigUyBggDEEUYOTIHCAQQABiABDIHCAUQLhiABDIHCAYQABiABDIHCAcQABiABDIJCAgQABgKGIAEMgkICRAAGAoYgATSAQoxNjkwNWowajE1qAIMsAIB8QWjlxl85iD_VA&amp;sourceid=chrome&amp;ie=UTF-8\">https:\/\/www.google.com\/search?q=elchiq&amp;oq=elch&amp;gs_l<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cu\u00e1ntos h\u00e9roes y cu\u00e1ntos villanos. Cu\u00e1ntos protagonistas. Cu\u00e1ntos ilustres y cu\u00e1ntos pr\u00f3fugos de la Efem\u00e9rides de hace 40 a\u00f1os. Y un reparto en blanco para las efem\u00e9rides de este mi\u00e9rcoles cuando&nbsp;<a href=\"https:\/\/espndeportes.espn.com\/futbol\/equipo?id=202\">Argentina<\/a>&nbsp;e Inglaterra jueguen la segunda Semifinal de esta Copa del Mundo 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nombres. Her\u00e1ldica. En voz de Serrat, \u201cel prohombre y el gusano bailan y se dan la mano\u201d. H\u00e9roes, villanos, circunstancias. Pasiones de cancha, pasiones intrusas. Sentimiento de patria. Invasores e invadidos. Desfile enlutado, luto sin desfile.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"791\" src=\"https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-55-1024x791.jpg\" alt=\"\" class=\"wp-image-11850\" srcset=\"https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-55-1024x791.jpg 1024w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-55-300x232.jpg 300w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-55-768x593.jpg 768w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-55-1536x1187.jpg 1536w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-55.jpg 1650w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto protagonista, de botines blancos y botas manchadas. La Semifinal. La antesala de retar a Espa\u00f1a. Maradona. La Mano de Dios. La sumisi\u00f3n de la Guardia de la Reina. El Gol del Siglo. Las Malvinas. The Falkland Islands.&nbsp;<a href=\"https:\/\/espndeportes.espn.com\/futbol\/jugador\/_\/id\/45843\/lionel-messi\">Lionel Messi<\/a>, el heredero.&nbsp;<a href=\"https:\/\/espndeportes.espn.com\/futbol\/jugador\/_\/id\/142200\/harry-kane\">Harry Kane<\/a>&nbsp;y&nbsp;<a href=\"https:\/\/espndeportes.espn.com\/futbol\/jugador\/_\/id\/291281\/jude-bellingham\">Jude Bellingham<\/a>, presuntos vindicativos. Infantino y sus torcidas decisiones. El VAR de la paja en el ojo ajeno. Beckham y el divorcio entre su chequera en Miami y su honramiento como Sir de su Majestad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Camiseta de un fan argentino con los rostros de Diego Maradona y Lionel Messi.&nbsp;Carl Recine\/Getty Images<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tantos protagonistas de un largometraje. Hay un escenario: Atlanta, la cuna de Martin Luther King, quien en diciembre de 1964 estremeci\u00f3 a los ingleses imprec\u00e1ndolos sobre el racismo. No hay gui\u00f3n, solo 90 o 120 p\u00e1ginas v\u00edrgenes, tal vez con un anexo de penaltis, donde un tipo, Dibu Mart\u00ednez, es un prestidigitador en typos (error tipogr\u00e1fico), y se especializa en escribir los renglones torcidos ante el manch\u00f3n de la gloria y la tragedia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ha dicho Lionel Scaloni que enfrentar este mi\u00e9rcoles a Inglaterra \u201ces un partido m\u00e1s\u201d. S\u00ed, mentiras piadosas. La prudencia y el recato evitan conflagraciones inoportunas, en sitios inoportunos y en momentos inoportunos. Ciertamente las 649 familias argentinas enlutadas hace 44 a\u00f1os deben haber derramado una nueva l\u00e1grima. Pero, seguramente, en la intimidad gravitante del vestidor, Scaloni y sus huestes transpiran, desde la sangre hasta el cerebro, que es m\u00e1s, much\u00edsimo m\u00e1s, que un partido de futbol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y seguramente se yergue la estampa del Diego, el de las dos versiones, el truhan del gol il\u00edcito que \u00e9l mismo endos\u00f3 a Dios, y despu\u00e9s, su \u00bfcabalgata o galopada?, hist\u00f3rico, memorable, entre el ballet del mexicano Isaac Hern\u00e1ndez y los pasos perfectamente invasivos de tango de El Cachafaz.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"791\" src=\"https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-56-1024x791.jpg\" alt=\"\" class=\"wp-image-11851\" srcset=\"https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-56-1024x791.jpg 1024w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-56-300x232.jpg 300w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-56-768x593.jpg 768w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-56-1536x1187.jpg 1536w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/Pub-inm-nuevo-56.jpg 1650w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Porque ah\u00ed, este mi\u00e9rcoles, estar\u00e1 Maradona, desde tres palcos irreconciliables. En el cielo de los futbolistas, el purgatorio de los seres humanos y el infierno de los irredentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este oficio del periodismo bendijo mi presencia aquel 22 de junio de 1986. Durante esa Copa del Mundo, con El Heraldo de M\u00e9xico, viv\u00eda y me desviv\u00eda, entre M\u00e9xico que entrenaba en Toluca y Argentina que entrenaba en Coapa. Esa tarde, recuerdo v\u00edvidamente el segundo gol del Diego. In crescendo. Era un Quijote hecho Centauro. A mi lado estaba Andr\u00e9s Cantor, entonces corresponsal de El Gr\u00e1fico. En la fila de atr\u00e1s, decanos del periodismo argentino: Juvenal (Julio C\u00e9sar Pasquato), On\u00e9sime, Cherquis Bialo. Poes\u00eda de El Gr\u00e1fico.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"213\" src=\"https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/pub-dolofen-nuevo-12-1024x213.jpg\" alt=\"\" class=\"wp-image-11852\" srcset=\"https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/pub-dolofen-nuevo-12-1024x213.jpg 1024w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/pub-dolofen-nuevo-12-300x63.jpg 300w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/pub-dolofen-nuevo-12-768x160.jpg 768w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/pub-dolofen-nuevo-12.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme Maradona sembraba de cad\u00e1veres ingleses la cancha del Estadio Azteca, y a lo lejos, como diez filas atr\u00e1s, se desbocaba entre un silencio admirativo y expectante, la narraci\u00f3n poderosa de V\u00edctor Hugo Morales, ah\u00ed, as\u00ed, los m\u00e1s de 120 mil aficionados empezaban a ponerse de pie. La \u00faltima cachetada del Diego, la red y la explosi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volteo sorprendido hacia atr\u00e1s. Por los gritos repetitivos, los alaridos incontenibles, las profanas exaltaciones: \u201cHijo de puta, hijo de puta, hijo de puta\u201d. Gimoteaban, alardeaban, lloraban, imploraban, festejaban, alucinaban, ellos, los genios de la escritura en El Gr\u00e1fico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Volteo a preguntarle a Andr\u00e9s Cantor sobre qu\u00e9 ocurr\u00eda, por qu\u00e9 insultaban a Maradona. Con el rostro abotagado por esa densa mezcla del j\u00fabilo y el llanto, que es tanta que duele, me explic\u00f3: \u201cAs\u00ed como ustedes los mexicanos dicen con admiraci\u00f3n \u2018\u00e9ste es un hijo de la chingada\u2019, es lo mismo, es admiraci\u00f3n pura\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuarenta a\u00f1os despu\u00e9s, nada ha cambiado, aunque todo est\u00e9 cambiado. Hoy hay nuevos actores, pero permanecen algunos de aquellos de 1986. Maradona. La Mano de Dios. La sumisi\u00f3n de la Guardia de la Reina. El Gol del Siglo. Las Malvinas. The Falkland Islands. Messi, el heredero. Kane y Bellingham, presuntos vindicativos. Infantino y sus torcidas decisiones. El VAR de la paja en el ojo ajeno.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"213\" src=\"https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/pub-dolofen-nuevo-13-1024x213.jpg\" alt=\"\" class=\"wp-image-11853\" srcset=\"https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/pub-dolofen-nuevo-13-1024x213.jpg 1024w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/pub-dolofen-nuevo-13-300x63.jpg 300w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/pub-dolofen-nuevo-13-768x160.jpg 768w, https:\/\/elchiq.com\/wp-content\/uploads\/2026\/07\/pub-dolofen-nuevo-13.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Y claro, a la vuelta de la esquina, Espa\u00f1a, que se deshizo f\u00e1cilmente de Francia. Y que sabe que cualquiera, Argentina o Inglaterra, llegar\u00e1 exhausta, pero fortalecida. Nada nutre mejor que la sangre humeante del enemigo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y ah\u00ed, seguramente, desde alg\u00fan lugar, el Diego aguardar\u00e1 como en aquella \u00e9poca \u2013hace 40 a\u00f1os&#8211;, millones de argentinos, desde ah\u00ed, desde el palco del Diego artista, del Diego pecador y del Diego eterno, aguardar\u00e1 con un rezongo similar a ese de 1986, esperando que el heredero, que Lionel Messi, lo merezca, ese blas\u00f3n popular, ese galard\u00f3n de potrero, esa condecoraci\u00f3n her\u00e1ldica: \u201cEs un hijo de p\u2026\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lea tambi\u00e9n:LA COPA DEL MUNDO EST\u00c1 ROMPIENDO TODOS LOS R\u00c9CORDS. https:\/\/elchiq.com\/index.php\/2026\/06\/22\/la-copa-del-mundo-esta-rompiendo-todos-los-records\/<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">www.elchiq.com https:\/\/www.google.com\/search?q=elchiq&amp;oq=elch&amp;gs_l<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escuche la decembrina: https:\/\/ladecembrina.radio12345com\/google_vignette<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00edganos en Facebook, Instagram, Telegram, Twitch, Discord, Linkedin, Flipboard, Mastodon,YouTube, X, Spotify, TikTok, Bluesky y nuestro canal de WhatsApp, para que reciba noticias de \u00faltima hora y m\u00e1s contenidos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Argentina e Inglaterra reviven la rivalidad que se intensific\u00f3 en el Mundial de M\u00e9xico en 1986. Por: redacci\u00f3n ESPN y elchiq.com\u00a0 https:\/\/www.google.com\/search?q=elchiq&amp;oq=elch&amp;gs_l Cu\u00e1ntos h\u00e9roes y cu\u00e1ntos villanos. Cu\u00e1ntos protagonistas. Cu\u00e1ntos ilustres y cu\u00e1ntos pr\u00f3fugos de la Efem\u00e9rides de hace 40 a\u00f1os. Y un reparto en blanco para las efem\u00e9rides de este mi\u00e9rcoles cuando&nbsp;Argentina&nbsp;e Inglaterra jueguen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11848","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/elchiq.com\/index.php\/wp-json\/wp\/v2\/posts\/11848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elchiq.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elchiq.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elchiq.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elchiq.com\/index.php\/wp-json\/wp\/v2\/comments?post=11848"}],"version-history":[{"count":1,"href":"https:\/\/elchiq.com\/index.php\/wp-json\/wp\/v2\/posts\/11848\/revisions"}],"predecessor-version":[{"id":11854,"href":"https:\/\/elchiq.com\/index.php\/wp-json\/wp\/v2\/posts\/11848\/revisions\/11854"}],"wp:attachment":[{"href":"https:\/\/elchiq.com\/index.php\/wp-json\/wp\/v2\/media?parent=11848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elchiq.com\/index.php\/wp-json\/wp\/v2\/categories?post=11848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elchiq.com\/index.php\/wp-json\/wp\/v2\/tags?post=11848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}